{"id":104336,"date":"2025-11-05T16:23:05","date_gmt":"2025-11-05T15:23:05","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=104336"},"modified":"2025-11-07T15:45:44","modified_gmt":"2025-11-07T14:45:44","slug":"padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/","title":{"rendered":"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo"},"content":{"rendered":"<p data-start=\"280\" data-end=\"721\"><strong>\u00a0Nel Padiglione 10<\/strong> di Fieracavalli &#8211; oltre l&#8217;area dedicata <span class=\"NormalTextRun BCX8 SCXW259433455\">alla biodiversit\u00e0 delle razze italiane e morfologia americana &#8211; prende vita l&#8217;<\/span><strong>Horse Friendly Arena<\/strong>, lo spazio che dal 2019 spiega a professionisti, famiglie e bambini cosa significhi davvero prendersi cura del cavallo, fisicamente e mentalmente.<\/p>\n<p data-start=\"280\" data-end=\"721\">Non un\u2019esibizione, ma un percorso di <strong>educazione<\/strong> e <strong>consapevolezza<\/strong> costruito per mostrare come la <strong>relazione tra uomo e cavallo <\/strong>nasca dall\u2019<strong>ascolto <\/strong>e dalla<strong> fiducia.<\/strong><\/p>\n<p data-start=\"723\" data-end=\"1123\">A guidare l\u2019arena \u00e8 <strong>Umberto Scotti,<\/strong> il <em>\u201csussurratore di cavalli\u201d<\/em>, che porta con s\u00e9 <strong>quattro<\/strong> <strong>scuole<\/strong>: il<strong> Gruppo Italiano \u00c9cole de L\u00e9g\u00e8ret\u00e9,<\/strong> <strong>Chiara Angelini e Fausto Sturaro<\/strong>, l\u2019<strong>Accademia Equestre Italiana e l\u2019Equitazione Classica in Leggerezza.<\/strong><\/p>\n<p data-start=\"723\" data-end=\"1123\">&#8220;<em>Abbiamo le migliori scuole di addestramento del settore, unite nel mostrare come la comunicazione e la comprensione dei comportamenti dell\u2019animale siano le chiavi di lettura per costruire un rapporto autentico e armonico con il cavallo&#8221;. <\/em>Afferma l&#8217;<em>horse whisperer<\/em> Umberto <strong>Scotti<\/strong>.<\/p>\n<p data-start=\"1125\" data-end=\"1874\">Da <strong>gioved\u00ec<\/strong> a <strong>sabato<\/strong> le attivit\u00e0 si aprono ogni mattina, dalle <strong>9 alle 11,<\/strong> con la <strong>movimentazione<\/strong> libera dei cavalli AIQH, seguita dalle sessioni delle scuole dell\u2019arena: prima<strong> Massimo Basili con l\u2019Equitazione Classica in Leggerezza<\/strong> fino alle 11.45, poi l<strong>\u2019Accademia Equestre Italiana<\/strong> fino alle 12.15, il <strong>Gruppo Italiano \u00c9cole de L\u00e9g\u00e8ret\u00e9<\/strong> fino alle 13 e, a seguire, la dimostrazione di comunicazione con <strong>Chiara Angelini e Fausto Sturaro<\/strong>. Dopo una breve pausa dedicata alla movimentazione del terreno, il pomeriggio \u2013 dalle 13.30 alle 17.30 \u2013 \u00e8 riservato ad <strong>ASI<\/strong> e alle <strong>discipline<\/strong> <strong>integrate<\/strong>.<\/p>\n<p data-start=\"1125\" data-end=\"1874\">In <strong>chiusura<\/strong> di giornata, dalle 19 alle 21, spazio alla movimentazione dei cavalli <strong>Reining<\/strong>.<\/p>\n<p data-start=\"1876\" data-end=\"2219\">La <strong>domenica<\/strong> la mattinata si apre con la <strong>terza manche<\/strong> degli spettacoli del GIA, seguiti dal ritorno delle sessioni didattiche delle scuole: Basili, il Gruppo \u00c9cole de L\u00e9g\u00e8ret\u00e9, Angelini e Sturaro e l\u2019Accademia Equestre Italiana si alternano fino alle 19, mantenendo attivi gli spazi della Horse Friendly Arena anche nell\u2019ultimo giorno di fiera.<\/p>\n<p data-start=\"1876\" data-end=\"2219\">Ti aspettiamo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Nel Padiglione 10 di Fieracavalli &#8211; oltre l&#8217;area dedicata alla biodiversit\u00e0 delle razze italiane e morfologia americana &#8211; prende vita l&#8217;Horse Friendly Arena, lo spazio che dal 2019 spiega a professionisti, famiglie e bambini cosa significhi davvero prendersi cura del cavallo, fisicamente e mentalmente. Non un\u2019esibizione, ma un percorso di educazione e consapevolezza costruito per [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":104342,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[864,1232],"tags":[],"class_list":["post-104336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-horse-friendly","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo - Fieracavalli<\/title>\n<meta name=\"description\" content=\"Horse Friendly\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo - Fieracavalli\" \/>\n<meta property=\"og:description\" content=\"Horse Friendly\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T15:23:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-07T14:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo\",\"datePublished\":\"2025-11-05T15:23:05+00:00\",\"dateModified\":\"2025-11-07T14:45:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/\"},\"wordCount\":318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg\",\"articleSection\":[\"Horse Friendly\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/\",\"name\":\"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg\",\"datePublished\":\"2025-11-05T15:23:05+00:00\",\"dateModified\":\"2025-11-07T14:45:44+00:00\",\"description\":\"Horse Friendly\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/horse-friendly\\\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo - Fieracavalli","description":"Horse Friendly","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/","og_locale":"it_IT","og_type":"article","og_title":"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo - Fieracavalli","og_description":"Horse Friendly","og_url":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2025-11-05T15:23:05+00:00","article_modified_time":"2025-11-07T14:45:44+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg","type":"image\/jpeg"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo","datePublished":"2025-11-05T15:23:05+00:00","dateModified":"2025-11-07T14:45:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/"},"wordCount":318,"commentCount":0,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg","articleSection":["Horse Friendly","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/","url":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/","name":"Padiglione 10: la Horse Friendly Arena insegna a capire il cavallo - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg","datePublished":"2025-11-05T15:23:05+00:00","dateModified":"2025-11-07T14:45:44+00:00","description":"Horse Friendly","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/horse-friendly\/padiglione-10-la-horse-friendly-arena-insegna-a-capire-il-cavallo\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Fieracavalli2024_Veronafiere_EnneviFoto_048.jpg","width":1200,"height":800},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/104336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=104336"}],"version-history":[{"count":4,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/104336\/revisions"}],"predecessor-version":[{"id":104347,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/104336\/revisions\/104347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/104342"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=104336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=104336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=104336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}