{"id":105247,"date":"2025-11-09T14:29:11","date_gmt":"2025-11-09T13:29:11","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=105247"},"modified":"2025-11-09T14:29:11","modified_gmt":"2025-11-09T13:29:11","slug":"nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/","title":{"rendered":"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli"},"content":{"rendered":"<p><strong data-start=\"211\" data-end=\"228\">Nico Acampora<\/strong> &#8211; fondatore di Pizza Aut &#8211; \u00e8 passato a trovare gli amici di <strong data-start=\"262\" data-end=\"275\">Apen\u2019Down<\/strong>, l\u2019impresa sociale che lavora per l\u2019<strong>inclusione<\/strong> e l\u2019<strong>inserimento lavorativo<\/strong> di persone con disabilit\u00e0.<\/p>\n<p>&#8220;Oggi sono a Fieracavalli perch\u00e9 sapevo che c&#8217;erano gli amici up and down, allora sono voluto venire a omaggiare il loro prezioso lavoro. Mio figlio per un paio d&#8217;anni \u00e8 andato a cavallo e ne ha tratto un grande beneficio, soprattutto per il suo umore.&#8221;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.youtube.com\/watch?v=PAZZA6yx_vo&amp;list=PLUh79EQXIjy7TqDePdiBr-ElXGeZ_ZhVH&amp;index=6\"><strong>CONTINUA A GUARDARE L&#8217;INTERVISTA<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nico Acampora &#8211; fondatore di Pizza Aut &#8211; \u00e8 passato a trovare gli amici di Apen\u2019Down, l\u2019impresa sociale che lavora per l\u2019inclusione e l\u2019inserimento lavorativo di persone con disabilit\u00e0. &#8220;Oggi sono a Fieracavalli perch\u00e9 sapevo che c&#8217;erano gli amici up and down, allora sono voluto venire a omaggiare il loro prezioso lavoro. Mio figlio per [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":105250,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1232],"tags":[],"class_list":["post-105247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli - Fieracavalli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli - Fieracavalli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T13:29:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-09-142300.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli\",\"datePublished\":\"2025-11-09T13:29:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/\"},\"wordCount\":94,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Screenshot-2025-11-09-142300.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/\",\"name\":\"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Screenshot-2025-11-09-142300.png\",\"datePublished\":\"2025-11-09T13:29:11+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/news\\\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Screenshot-2025-11-09-142300.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Screenshot-2025-11-09-142300.png\",\"width\":1200,\"height\":617},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli - Fieracavalli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/","og_locale":"it_IT","og_type":"article","og_title":"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli - Fieracavalli","og_url":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2025-11-09T13:29:11+00:00","og_image":[{"width":1200,"height":617,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-09-142300.png","type":"image\/png"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli","datePublished":"2025-11-09T13:29:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/"},"wordCount":94,"commentCount":0,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-09-142300.png","articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/","url":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/","name":"Nico Acampora fa visita agli amici di Apen\u2019Down a Fieracavalli - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-09-142300.png","datePublished":"2025-11-09T13:29:11+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/news\/nico-acampora-fa-visita-agli-amici-di-apendown-a-fieracavalli\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-09-142300.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-09-142300.png","width":1200,"height":617},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/105247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=105247"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/105247\/revisions"}],"predecessor-version":[{"id":105252,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/105247\/revisions\/105252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/105250"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=105247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=105247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=105247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}