{"id":35539,"date":"2021-11-12T12:00:00","date_gmt":"2021-11-12T12:00:00","guid":{"rendered":"https:\/\/www.fieracavalli.it\/non-categorizzato\/paradriving-2021-da-modena-a-verona-in-carrozza\/"},"modified":"2023-07-14T16:28:04","modified_gmt":"2023-07-14T14:28:04","slug":"paradriving-2021-da-modena-a-verona-in-carrozza","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/","title":{"rendered":"Paradriving 2021: da Modena a Verona in carrozza"},"content":{"rendered":"<p>Arrivati a Fieracavalli i protagonisti del viaggio Modena Verona del progetto <strong>Paradriving 2021<\/strong>.<\/p>\n<p>Partiti marted\u00ec 9 dalle <strong>Scuderie Ducali presso l\u2019Accademia Militare di Modena<\/strong>, hanno proseguito per Carpi, Novi di Modena, San Benedetto Po\u2019, Casteldario, Sorg\u00e0, fino ad arrivare a Isola della Scala dove hanno pernottato ieri, gioved\u00ec 11, per giungere oggi in fiera a Verona.<\/p>\n<p>&nbsp;<\/p>\n<p>Il progetto con focus sull\u2019equitazione integrata, mirata al superamento di barriere fisiche e relazionali, ha coinvolto persone con disabilit\u00e0 motorie e psichiche che hanno affrontato i 105 km del percorso Modena \u2013 Verona a bordo di carrozze trainate da pariglie di cavalli di razze italiane, per rafforzare il valore dell\u2019attivit\u00e0 allevatoriale italiana. Per dare un significato ampio anche a livello territoriale all\u2019evento, sono state coinvolte per ogni tappa ragazzi disabili diversi, residenti nel territorio attraversato, che si sono dati il cambio a bordo delle carrozze.<\/p>\n<p>&nbsp;<\/p>\n<p>Un viaggio che \u00e8 stato l\u2019opportunit\u00e0 per approfondire i temi legati alla tradizione, al territorio e all\u2019inclusione sociale. Il mondo degli attacchi ha infatti in s\u00e9 molti aspetti utili per oltrepassare i limiti fisici, relazionali e a volte anche culturali che impediscono relazioni e apprendimenti corretti. L\u2019attenzione per la tradizione e la cultura, la condivisione di spazi ristretti dove \u00e8 fondamentale la comunicazione e la collaborazione rendono particolarmente efficaci progetti di integrazione e valorizzazione delle capacit\u00e0 della persona con un impatto positivo sull\u2019autostima e la disponibilit\u00e0 al lavoro di gruppo.<\/p>\n<p>In questa occasione sport e vita in una carrozza si sono uniti, dando origine ad una esperienza unica!<\/p>\n<p>&nbsp;<\/p>\n<p>Un progetto di <strong>Asd Equilandia Club<\/strong> e <strong>Azienda Agricola Villa Forni<\/strong> reso possibile anche grazie alla sinergia con numerosi altri soggetti quali <strong>ASAM Onlus<\/strong>, l\u2019<strong>Accademia Militare di Modena<\/strong>, le Amministrazioni dei paesi attraversati, la \u00a0<strong>FISE<\/strong>, <strong>ANAC<\/strong> (Associazione nazionale arma di cavalleria, sezione Modena.), la fondazione <strong>Societ\u00e0 Cattolica di Assicurazioni<\/strong> e la <strong>Fondazione VIVO<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna il progetto sull\u2019equitazione integrata rivolto a persone con disabilit\u00e0 per il superamento delle barriere fisiche e relazionali<\/p>\n","protected":false},"author":3,"featured_media":36502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[832,865],"tags":[],"class_list":["post-35539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-cavallo-della-sostenibilita","category-riding-togheter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paradriving 2021: da Modena a Verona in carrozza - Fieracavalli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paradriving 2021: da Modena a Verona in carrozza - Fieracavalli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T14:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/\"},\"author\":{\"name\":\"Nicola\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/7b314d37bf1a4e984122ace7a2fedcb1\"},\"headline\":\"Paradriving 2021: da Modena a Verona in carrozza\",\"datePublished\":\"2021-11-12T12:00:00+00:00\",\"dateModified\":\"2023-07-14T14:28:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/\"},\"wordCount\":316,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg\",\"articleSection\":[\"A cavallo della sostenibilit\u00e0\",\"Riding togheter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/\",\"name\":\"Paradriving 2021: da Modena a Verona in carrozza - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg\",\"datePublished\":\"2021-11-12T12:00:00+00:00\",\"dateModified\":\"2023-07-14T14:28:04+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/paradriving-2021-da-modena-a-verona-in-carrozza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/7b314d37bf1a4e984122ace7a2fedcb1\",\"name\":\"Nicola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g\",\"caption\":\"Nicola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paradriving 2021: da Modena a Verona in carrozza - Fieracavalli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/","og_locale":"it_IT","og_type":"article","og_title":"Paradriving 2021: da Modena a Verona in carrozza - Fieracavalli","og_url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2021-11-12T12:00:00+00:00","article_modified_time":"2023-07-14T14:28:04+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg","type":"image\/jpeg"}],"author":"Nicola","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nicola","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/"},"author":{"name":"Nicola","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/7b314d37bf1a4e984122ace7a2fedcb1"},"headline":"Paradriving 2021: da Modena a Verona in carrozza","datePublished":"2021-11-12T12:00:00+00:00","dateModified":"2023-07-14T14:28:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/"},"wordCount":316,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg","articleSection":["A cavallo della sostenibilit\u00e0","Riding togheter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/","url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/","name":"Paradriving 2021: da Modena a Verona in carrozza - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg","datePublished":"2021-11-12T12:00:00+00:00","dateModified":"2023-07-14T14:28:04+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/paradriving-2021-da-modena-a-verona-in-carrozza\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/Paradriving_Fieracavalli2021_EnneviFoto_Veronafiere_MXT0414-scaled-1.jpg","width":2560,"height":1707},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/7b314d37bf1a4e984122ace7a2fedcb1","name":"Nicola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g","caption":"Nicola"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/35539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=35539"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/35539\/revisions"}],"predecessor-version":[{"id":57707,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/35539\/revisions\/57707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/36502"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=35539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=35539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=35539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}