{"id":35592,"date":"2022-03-31T14:00:33","date_gmt":"2022-03-31T14:00:33","guid":{"rendered":"https:\/\/www.fieracavalli.it\/non-categorizzato\/riding-the-blue-un-cavallo-per-amico\/"},"modified":"2023-07-14T16:27:54","modified_gmt":"2023-07-14T14:27:54","slug":"riding-the-blue-un-cavallo-per-amico","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/","title":{"rendered":"Riding the Blue &#8211; Un cavallo per amico"},"content":{"rendered":"<p>Continua l\u2019impegno nel sociale di Fieracavalli. Dopo la firma ufficiale, lo scorso anno, della versione <span class=\"TextRun SCXW26203029 BCX0\" lang=\"IT-IT\" xml:lang=\"IT-IT\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW26203029 BCX0\">2.0 del protocollo sperimentale nato nel 2019 e attuato in Veneto grazie alla collaborazione con l\u2019Azienda Ospedaliera Universitaria Integrata di Verona e l\u2019Unit\u00e0 Locale Socio-Sanitaria 9 Scaligera, i<\/span><\/span>n occasione della <strong>Giornata Mondiale della consapevolezza sull\u2019autismo<\/strong> del<strong> 2 aprile<\/strong>, Fieracavalli lancia la campagna di crowdfunding \u201c<strong>Riding the Blue \u2013 Un cavallo per amico\u201d<\/strong> \u00a0a favore del progetto sperimentale Riding the Blue\u00a0dedicato all\u2019<strong>ippoterapia<\/strong> per il trattamento dei bambini affetti dal <strong>Disturbo dello Spettro Autistico<\/strong> (ASD).<\/p>\n<p><span class=\"TextRun SCXW19343984 BCX0\" lang=\"IT-IT\" xml:lang=\"IT-IT\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW19343984 BCX0\">L\u2019intento \u00e8 quello di replicare la ricerca che promuove e valorizza i benefici della terapia assistita con il cavallo nei bambini affetti dal Disturbo dello Spettro Autistico, anche a livello nazionale, con il fine ultimo di far riconoscere questo tipo di terapia dal SSN (Servizio Sanitario Nazionale).<\/span><\/span><span class=\"EOP SCXW19343984 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span class=\"TextRun SCXW241024437 BCX0\" lang=\"IT-IT\" xml:lang=\"IT-IT\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW241024437 BCX0\">\u00abI risultati della ricerca presentati durante gli <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW241024437 BCX0\">Horse<\/span><span class=\"NormalTextRun SCXW241024437 BCX0\"> Digital Days di Fieracavalli 2020 hanno visto un miglioramento nei partecipanti del funzionamento in diverse aree del comportamento adattivo, un incremento della coordinazione motoria e dell\u2019abilit\u00e0 di processazione sensoriale con effetti sulla vita quotidiana &#8211; racconta il dott. Leonardo <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW241024437 BCX0\">Zoccante<\/span><span class=\"NormalTextRun SCXW241024437 BCX0\"> \u2013 vogliamo estendere dunque la sperimentazione a livello nazionale per dare spazio alle potenzialit\u00e0 degli Interventi Assistiti con il cavallo cos\u00ec da favorire l\u2019inclusione dei bambini nel tessuto sociale\u00bb.<\/span><\/span><span class=\"EOP SCXW241024437 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>A partire dal 2 aprile, sar\u00e0 possibile donare sulla piattaforma Rete del Dono <a href=\"http:\/\/www.retedeldono.it\">www.retedeldono.it<\/a> per contribuire al raggiungimento dell\u2019obiettivo finale prefissato di <strong>30mila euro<\/strong>. Scopo della campagna &#8211; che terminer\u00e0 sabato 28 maggio con una cerimonia di chiusura in programma durante l\u201989<sup>a<\/sup> edizione di <strong>Piazza di Siena<\/strong> a Roma &#8211; \u00e8 quello di raccogliere fondi per finanziare un <strong>progetto interregionale<\/strong> che coinvolger\u00e0 diversi centri equestri italiani &#8211; selezionati grazie al supporto della <strong>Federazione Italiana Sport Equestri<\/strong> &#8211; e <strong>60 giovani affetti da ASD<\/strong> seguiti da un\u2019equipe multidisciplinare regionale. Le attivit\u00e0 messe in campo, con il supporto dell\u2019<strong>Associazione Nazionale Genitori perSone con Autismo <\/strong>e di <strong>EY Foundation<\/strong>, saranno basate sul metodo scaturito dallo studio <strong>Riding the Blue<\/strong>, progetto sperimentale coordinato dal <strong>Prof. Leonardo Zoccante<\/strong> e promosso da Fieracavalli con l\u2019obiettivo di evidenziare i benefici degli <strong>Interventi Assistiti con il cavallo<\/strong> nei bambini affetti da autismo. L\u2019intero ricavato dell\u2019iniziativa benefica verr\u00e0 devoluto ad Angsa, permettendo ai 60 soggetti selezionati di accedere al trattamento gratuitamente.<\/p>\n<p>Grazie ai risultati di questa pi\u00f9 ampia sperimentazione, sar\u00e0 possibile corroborare il valore clinico della ricerca condotta fino ad ora, con l\u2019ambizioso intento di far riconoscere l\u2019ippoterapia <strong>dal Servizio Sanitario Nazionale<\/strong> non solo come intervento integrativo, ma come una <strong>pratica <\/strong>efficace nel favorire lo sviluppo della persona con autismo.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la tua donazione, potrai regalare ore di ippoterapia a ragazzi di et\u00e0 compresa tra i 7-8 anni e i 15-16 anni.<br \/>\nInoltre, sono previsti tre premi per i donatori pi\u00f9 generosi:<br \/>\n<strong>&#8211; per le prime 150 donazioni superiori ai 50 euro, un ingresso per Fieracavalli Verona, dal 3 al 6 novembre<br \/>\n&#8211; per le prime 56 donazioni superiori ai 300 euro, un &#8220;NFT Riding the Blue Cap\u201d e 2 biglietti per Fieracavalli Verona, dal 3 al 6 novembre.<br \/>\n&#8211; per le prime 8 donazioni superiori ai 1000 euro, un prestigioso \u201cRiding the Blue Cap\u201d di Kep Italia, un NFT e un invito speciale all\u201989esima edizione di Piazza di Siena dove ti sar\u00e0 consegnato il premio durante una cerimonia ufficiale il 28 maggio 2022.<\/strong><\/p>\n<p>Il NFT &#8211; Non Fungible Token &#8211; \u00e8 un asset digitale che rappresenta un oggetto del mondo reale, in questo caso i caschi KEP serigrafati. Ogni token \u00e8 unico e non replicabile.<\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/www.retedeldono.it\/it\/progetti\/ey-foundation-onlus\/riding-the-blue-un-cavallo-per-amico\"><strong>Fai la tua offerta!<\/strong><\/a><\/h4>\n<p style=\"text-align: center;\">&#8211; donazione minima 10\u20ac &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La campagna di crowdfunding di Fieracavalli a sostegno dei benefici dell\u2019ippoterapia nel trattamento dei Disturbi dello Spettro Autistico<\/p>\n","protected":false},"author":3,"featured_media":28116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[832,865],"tags":[],"class_list":["post-35592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-cavallo-della-sostenibilita","category-riding-togheter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riding the Blue - Un cavallo per amico - Fieracavalli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riding the Blue - Un cavallo per amico - Fieracavalli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T14:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T14:27:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/IMG_20200611_172805-scaled-e1648722347982.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1241\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/\"},\"author\":{\"name\":\"Nicola\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/7b314d37bf1a4e984122ace7a2fedcb1\"},\"headline\":\"Riding the Blue &#8211; Un cavallo per amico\",\"datePublished\":\"2022-03-31T14:00:33+00:00\",\"dateModified\":\"2023-07-14T14:27:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/\"},\"wordCount\":590,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20200611_172805-scaled-e1648722347982.jpg\",\"articleSection\":[\"A cavallo della sostenibilit\u00e0\",\"Riding togheter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/\",\"name\":\"Riding the Blue - Un cavallo per amico - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20200611_172805-scaled-e1648722347982.jpg\",\"datePublished\":\"2022-03-31T14:00:33+00:00\",\"dateModified\":\"2023-07-14T14:27:54+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-un-cavallo-per-amico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20200611_172805-scaled-e1648722347982.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20200611_172805-scaled-e1648722347982.jpg\",\"width\":2560,\"height\":1241},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/7b314d37bf1a4e984122ace7a2fedcb1\",\"name\":\"Nicola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g\",\"caption\":\"Nicola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riding the Blue - Un cavallo per amico - Fieracavalli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/","og_locale":"it_IT","og_type":"article","og_title":"Riding the Blue - Un cavallo per amico - Fieracavalli","og_url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2022-03-31T14:00:33+00:00","article_modified_time":"2023-07-14T14:27:54+00:00","og_image":[{"width":2560,"height":1241,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/IMG_20200611_172805-scaled-e1648722347982.jpg","type":"image\/jpeg"}],"author":"Nicola","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nicola","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/"},"author":{"name":"Nicola","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/7b314d37bf1a4e984122ace7a2fedcb1"},"headline":"Riding the Blue &#8211; Un cavallo per amico","datePublished":"2022-03-31T14:00:33+00:00","dateModified":"2023-07-14T14:27:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/"},"wordCount":590,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/IMG_20200611_172805-scaled-e1648722347982.jpg","articleSection":["A cavallo della sostenibilit\u00e0","Riding togheter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/","url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/","name":"Riding the Blue - Un cavallo per amico - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/IMG_20200611_172805-scaled-e1648722347982.jpg","datePublished":"2022-03-31T14:00:33+00:00","dateModified":"2023-07-14T14:27:54+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-un-cavallo-per-amico\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/IMG_20200611_172805-scaled-e1648722347982.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/09\/IMG_20200611_172805-scaled-e1648722347982.jpg","width":2560,"height":1241},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/7b314d37bf1a4e984122ace7a2fedcb1","name":"Nicola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a32eaa3fe51b2f359d1f98faf9a1098fc965a8e8bb92f7fee8b6f9d6ef353a78?s=96&d=mm&r=g","caption":"Nicola"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/35592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=35592"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/35592\/revisions"}],"predecessor-version":[{"id":57689,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/35592\/revisions\/57689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/28116"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=35592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=35592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=35592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}