{"id":53703,"date":"2022-11-03T15:59:11","date_gmt":"2022-11-03T15:59:11","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=53703"},"modified":"2023-07-14T16:27:23","modified_gmt":"2023-07-14T14:27:23","slug":"a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/","title":{"rendered":"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre"},"content":{"rendered":"<p><span data-contrast=\"auto\">Oggi vi aspettano i primi talk\u00a0nell\u2019area forum AGSM AIM A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre al Padiglione 4. Un punto di raccolta, snodo e confronto sui numerosi progetti nati e partiti dalla fiera, con l\u2019obiettivo di tenere acceso il dialogo sul <\/span><b><span data-contrast=\"auto\">futuro sostenibile<\/span><\/b><span data-contrast=\"auto\"> del settore.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Sar\u00e0 questo spazio, allestito con materiali di riuso e realizzati dalla falegnameria della Casa Circondariale di Montorio, ad ospitare interviste, incontri e tavole rotonde.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Obiettivo: confrontarsi sull\u2019importanza del rapporto terapeutico tra uomo e cavallo, sulle modalit\u00e0 di abbattimento di costi energetici e ambientali, sull\u2019inclusione sociale delle categorie pi\u00f9 fragili e sulla promozione del turismo equestre come pratica etica e consapevole, tutto\u202fgrazie alla collaborazione tra Reverse, UISP, Ecopneus, Teleambiente e Final Furlong.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Primo appuntamento, oggi alle <\/span><b><span data-contrast=\"auto\">14.00<\/span><\/b><span data-contrast=\"auto\">, con <\/span><b><span data-contrast=\"auto\">Progetto educazione, cura e gestione a terra del cavallo<\/span><\/b><span data-contrast=\"auto\">, a cura di <\/span><b><span data-contrast=\"auto\">Final Furlong<\/span><\/b><span data-contrast=\"auto\"> e, a\u00a0seguire, alle <\/span><b><span data-contrast=\"auto\">15.30<\/span><\/b><span data-contrast=\"auto\"> vi aspetta <\/span><b><span data-contrast=\"auto\">A cavallo della sostenibilit\u00e0, introduzione al format 2022 con focus sul progetto equestre interno della Casa Circondariale di Verona<\/span><\/b><span data-contrast=\"auto\">, a cura di <\/span><b><span data-contrast=\"auto\">Reverse<\/span><\/b><span data-contrast=\"auto\">. Gli ospiti, tra cui la direttrice della Casa Circondariale di Montorio, l\u2019Assessore alle Politiche Giovanili Jacopo Buffolo e Linda Fabrello di Horse Valley parleranno del progetto di reinserimento sociale dei detenuti attraverso il lavoro e della consegna dei diplomi a chi ha partecipato al corso di tecnico di scuderia con profitto. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Venerd\u00ec 4<\/span><\/b><span data-contrast=\"auto\"> novembre alle 9.30 e alle 14.00 l\u2019area forum ospita il <\/span><b><span data-contrast=\"auto\">6^ Meeting Nazionale degli Interventi Assistiti con gli Animali<\/span><\/b><span data-contrast=\"auto\"> a cura di We Animals, oltre ad incontri a cura di UISP Ecopneus e Final Furlong.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Sabato 5<\/span><\/b><span data-contrast=\"auto\"> novembre focus sul <\/span><b><span data-contrast=\"auto\">turismo equestre<\/span><\/b><span data-contrast=\"auto\"> e il valore sociale del cavallo\u00a0con un talk sul Raid Monaco Verona a Cura di Reverse insieme a Horse Adventure, Natura a Cavallo e l\u2019esploratrice equestre Paola Giacomini, la presentazione delle ippovie urbane e rurali e un incontro sul Paradressage con Gea Einaudi.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Si chiude <\/span><b><span data-contrast=\"auto\">domenica 6<\/span><\/b><span data-contrast=\"auto\"> con diversi talk sulla<\/span><b><span data-contrast=\"auto\"> valorizzazione del mondo equestre<\/span><\/b><span data-contrast=\"auto\"> attraverso la comunicazione e progetti sociali. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\"><a href=\"https:\/\/www.fieracavalli.it\/it\/programma-talk\/\">Qui<\/a> il programma completo <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi vi aspettano i primi talk\u00a0nell\u2019area forum AGSM AIM A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre al Padiglione 4. Un punto di raccolta, snodo e confronto sui numerosi progetti nati e partiti dalla fiera, con l\u2019obiettivo di tenere acceso il dialogo sul futuro sostenibile del settore.\u00a0 Sar\u00e0 questo spazio, allestito [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":53727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[832],"tags":[],"class_list":["post-53703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-cavallo-della-sostenibilita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre - Fieracavalli<\/title>\n<meta name=\"description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre - Fieracavalli\" \/>\n<meta property=\"og:description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-03T15:59:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T14:27:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre\",\"datePublished\":\"2022-11-03T15:59:11+00:00\",\"dateModified\":\"2023-07-14T14:27:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/\"},\"wordCount\":342,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.png\",\"articleSection\":[\"A cavallo della sostenibilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/\",\"name\":\"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.png\",\"datePublished\":\"2022-11-03T15:59:11+00:00\",\"dateModified\":\"2023-07-14T14:27:23+00:00\",\"description\":\"A cavallo della sostenibilit\u00e0\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.png\",\"width\":1080,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre - Fieracavalli","description":"A cavallo della sostenibilit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/","og_locale":"it_IT","og_type":"article","og_title":"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre - Fieracavalli","og_description":"A cavallo della sostenibilit\u00e0","og_url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2022-11-03T15:59:11+00:00","article_modified_time":"2023-07-14T14:27:23+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/1.png","type":"image\/png"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre","datePublished":"2022-11-03T15:59:11+00:00","dateModified":"2023-07-14T14:27:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/"},"wordCount":342,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/1.png","articleSection":["A cavallo della sostenibilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/","url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/","name":"A cavallo della sostenibilit\u00e0 | Dialoghi sul futuro sostenibile del mondo equestre - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/1.png","datePublished":"2022-11-03T15:59:11+00:00","dateModified":"2023-07-14T14:27:23+00:00","description":"A cavallo della sostenibilit\u00e0","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-cavallo-della-sostenibilita-dialoghi-sul-futuro-sostenibile-del-mondo-equestre\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/1.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/1.png","width":1080,"height":1080},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/53703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=53703"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/53703\/revisions"}],"predecessor-version":[{"id":57595,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/53703\/revisions\/57595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/53727"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=53703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=53703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=53703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}