{"id":53809,"date":"2022-11-04T11:17:05","date_gmt":"2022-11-04T11:17:05","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=53809"},"modified":"2023-07-14T16:27:22","modified_gmt":"2023-07-14T14:27:22","slug":"corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/","title":{"rendered":"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio"},"content":{"rendered":"<p><span data-contrast=\"auto\">Si \u00e8 svolto ieri, nella giornata di inaugurazione dell\u2019area forum AGSM AIM A cavallo della sostenibilit\u00e0 al Padiglione 4, un talk a cura di Reverse con focus sul progetto di reinserimento sociale all\u2019interno della Casa Circondariale di Montorio. In questa occasione anche la consegna simbolica dei diplomi di tecnico di scuderia ai detenuti, non presenti in fiera, tra la direttrice del carcere di Montorio Mariagrazia Bregoli e Linda Fabrello di Horse Valley.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Federica Collato, dopo aver introdotto il format di quest\u2019anno e l\u2019area dove si svolgeranno gli incontri su sostenibilit\u00e0 sociale e ambientale nel mondo equestre, ha lasciato la parola agli invitati.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Presente al tavolo Mariagrazia Bregoli per spiegare l\u2019importanza di un\u2019azione concreta per il reinserimento dei detenuti in societ\u00e0. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00abIl carcere per molti rappresenta un luogo isolato, chiuso, ma non \u00e8 cos\u00ec. Noi cittadini comuni consideriamo diverso chi ha commesso un reato, basandoci sul certificato penale, ma i valori della nostra societ\u00e0 sono l\u2019inclusione sociale e il rispetto della diversit\u00e0, e i compiti del carcere sono favorire il reinserimento e allontanare gli ostacoli di impedimento all\u2019inclusione\u00bb &#8211; commenta Bregoli. \u00abEssere presenti e collaborare con Fieracavalli \u00e8 straordinario, perch\u00e9 una fiera internazionale cos\u00ec importante accetta e accoglie i detenuti con rispetto e senza pregiudizi. Con questo progetto il carcere non \u00e8 pi\u00f9 un luogo in cui rimanere in attesa della fine della pena, ma un posto in cui cambiare vita e imparare qualcosa di nuovo\u00bb.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Al tavolo anche Linda Fabrello di Horse Valley, che opera a Corte Molon ormai da 10 anni, un luogo magnifico messo a disposizione del Comune di Verona diventato un maneggio sociale nel senso pi\u00f9 ampio del termine. Focus dei progetti attivi \u00e8 la terapia assistita con gli animali per disabilit\u00e0, adolescenti in difficolt\u00e0 e per il reinserimento in societ\u00e0 dei detenuti sottolineando sempre il benessere e la socialit\u00e0 che il cavallo sa donare. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La presenza di Horse Valley all\u2019interno della Casa Circondariale non \u00e8 solo attraverso l\u2019inserimento di 3 box, inaugurati nel 2019 grazie anche a Fieracavalli, ma anche con la presenza di corsi che prevedono il contatto tra i detenuti e i cavalli. I ragazzi scelgono volontariamente di partecipare e prendersi cura dei cavalli, avendo inoltre la possibilit\u00e0 di acquisire competenze che aiuteranno ad inserirsi nel mondo del lavoro .<\/span><\/p>\n<p><span class=\"TextRun SCXW71808063 BCX0\" lang=\"IT-IT\" xml:lang=\"IT-IT\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW71808063 BCX0\"><span data-contrast=\"auto\">\u00ab<\/span>Il corso di <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW71808063 BCX0\">quest\u2019anno<\/span><span class=\"NormalTextRun SCXW71808063 BCX0\"> diventa ancora pi\u00f9 ufficiale perch\u00e9<\/span><span class=\"NormalTextRun SCXW71808063 BCX0\"> permette di inserire i ragazzi in un albo nazionale di AICS (Associazione Italiana Cultura e Sport), ente che ci affilia. L&#8217;ente permette a chiunque abbia un maneggio di andare a vedere chi poter chiamare come lavoratore, dando una grandissima possibilit\u00e0 ai detenuti. Il corso che facciamo, da diversi anni, ha p<\/span><span class=\"NormalTextRun SCXW71808063 BCX0\">ermesso ad almeno 3-4 persone di trovare lavoro chi come maniscalco, chi come aiuto scuderia, un momento opportunit\u00e0 per ragazzi importantissima<span data-contrast=\"auto\">\u00bb &#8211; racconta Linda Fabrello.\u00a0<\/span><\/span><\/span><\/p>\n<p>9 i detenuti che hanno completato il corso, ricevendo il diploma di tecnico di scuderia. Un numero estremamente alto, che d\u00e0 speranza e rende evidente l&#8217;importanza di questo progetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolto ieri, nella giornata di inaugurazione dell\u2019area forum AGSM AIM A cavallo della sostenibilit\u00e0 al Padiglione 4, un talk a cura di Reverse con focus sul progetto di reinserimento sociale all\u2019interno della Casa Circondariale di Montorio. In questa occasione anche la consegna simbolica dei diplomi di tecnico di scuderia ai detenuti, non presenti [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":53814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[832],"tags":[],"class_list":["post-53809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-cavallo-della-sostenibilita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio - Fieracavalli<\/title>\n<meta name=\"description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio - Fieracavalli\" \/>\n<meta property=\"og:description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-04T11:17:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T14:27:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio\",\"datePublished\":\"2022-11-04T11:17:05+00:00\",\"dateModified\":\"2023-07-14T14:27:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/\"},\"wordCount\":507,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg\",\"articleSection\":[\"A cavallo della sostenibilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/\",\"name\":\"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg\",\"datePublished\":\"2022-11-04T11:17:05+00:00\",\"dateModified\":\"2023-07-14T14:27:22+00:00\",\"description\":\"A cavallo della sostenibilit\u00e0\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg\",\"width\":800,\"height\":534},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio - Fieracavalli","description":"A cavallo della sostenibilit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/","og_locale":"it_IT","og_type":"article","og_title":"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio - Fieracavalli","og_description":"A cavallo della sostenibilit\u00e0","og_url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2022-11-04T11:17:05+00:00","article_modified_time":"2023-07-14T14:27:22+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg","type":"image\/jpeg"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio","datePublished":"2022-11-04T11:17:05+00:00","dateModified":"2023-07-14T14:27:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/"},"wordCount":507,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg","articleSection":["A cavallo della sostenibilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/","url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/","name":"Corte Molon e Fieracavalli per la consegna dei diplomi ai detenuti della Casa Circondariale di Montorio - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg","datePublished":"2022-11-04T11:17:05+00:00","dateModified":"2023-07-14T14:27:22+00:00","description":"A cavallo della sostenibilit\u00e0","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/corte-molon-e-fieracavalli-per-la-consegna-dei-diplomi-ai-detenuti-della-casa-circondariale-di-montorio\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM19493.jpg","width":800,"height":534},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/53809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=53809"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/53809\/revisions"}],"predecessor-version":[{"id":57592,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/53809\/revisions\/57592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/53814"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=53809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=53809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=53809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}