{"id":54250,"date":"2022-11-05T14:49:24","date_gmt":"2022-11-05T14:49:24","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=54250"},"modified":"2023-07-14T16:27:14","modified_gmt":"2023-07-14T14:27:14","slug":"a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/","title":{"rendered":"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo"},"content":{"rendered":"<p><span data-contrast=\"auto\">Questa mattina, nello stand della Regione Veneto, si \u00e8 tenuta la quinta edizione della consegna del premio nazionale Carla Guglielmi della Fondazione Fevoss Santa Toscana, che premia il miglior lavoro di tesi sulla ricerca e lo studio sugli Interventi Assistiti con il Cavallo. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">L\u2019istituzione del premio \u00e8 un\u2019idea di Angelo Pasi, marito della stimata docente Carla Guglielmi, scomparsa qualche anno fa. Dalle sue due grandi passioni, quella per i cavalli e quella per i giovani, soprattutto in difficolt\u00e0, nasce il riconoscimento della Fondazioen Fevoss Santa Toscana per dare rilievo alla straordinaria relazione tra uomo e cavallo e alle ricerche nel settore degli interventi assistiti con questo animale.\u00a0 <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Il premio, in 5 anni, \u00e8 cresciuto moltissimo sia come partecipazione, viste le moltissime tesi inviate in risposta al bando della Fondazione, sia in termini di prestigio, perch\u00e9 il board scientifico si \u00e8 espanso, coinvolgendo professionisti, veterinari e professori universitari di tutta Italia. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Il riconoscimento \u00e8 stato consegnato nella cornice di Fieracavalli, partner che ha subito creduto nel progetto e ha voluto aiutare e realizzare questo sogno, oltre al sostegno di Regione Veneto.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Al tavolo, oltre ad Angelo Pasi, anche il presidente della Fondazione Fevoss Alfredo Dal Corso e il consigliere regionale del Veneto. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00c8 proprio il presidente Dal Corso a sottolineare l\u2019importanza di questo premio, festeggiando 5 anni di ricerca scientifica, ma anche il valore dell\u2019amicizia con una testimonianza: \u201cL\u2019amicizia d\u2019infanzia tra me e Angelo Pasi si \u00e8 sviluppata negli anni in et\u00e0 pi\u00f9 matura con l\u2019istituzione di questo premio. Il riconoscimento simboleggia il dolore che si trasforma in ricordo, che poi si trasforma in dono della ricerca. Questa moglie, che ha lasciato un vuoto nella sua casa, ha generato in qualche modo bene attraverso la ricerca scientifica.\u201d<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A premiare le tre studentesse un emozionato Angelo Pasi, insieme alla giuria.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La vincitrice dell\u2019edizione 2022 del premio Carla Guglielmi \u00e8 Stella Cavallini con la\u00a0tesi di laurea magistrale in scienze pedagogiche dal titolo \u201cEducare attraverso il rapporto con gli animali\u201d, discussa all\u2019universit\u00e0 degli studi di Verona. Il premio \u00e8 una borsa di studio del valore di 1.500 \u20ac e la nostra pubblicazione. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Menzione speciale, con una borsa di studio di \u20ac300 anche a Silvia Andreotti laureata all\u2019universit\u00e0 di Roma Niccol\u00f2 Cusano, e a Deborah Scarponi, laureata all\u2019Universit\u00e0 degli Studi di Peregia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa mattina, nello stand della Regione Veneto, si \u00e8 tenuta la quinta edizione della consegna del premio nazionale Carla Guglielmi della Fondazione Fevoss Santa Toscana, che premia il miglior lavoro di tesi sulla ricerca e lo studio sugli Interventi Assistiti con il Cavallo. \u00a0 L\u2019istituzione del premio \u00e8 un\u2019idea di Angelo Pasi, marito della stimata [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":54298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[832],"tags":[],"class_list":["post-54250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-cavallo-della-sostenibilita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo - Fieracavalli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo - Fieracavalli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-05T14:49:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T14:27:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo\",\"datePublished\":\"2022-11-05T14:49:24+00:00\",\"dateModified\":\"2023-07-14T14:27:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/\"},\"wordCount\":392,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg\",\"articleSection\":[\"A cavallo della sostenibilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/\",\"name\":\"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg\",\"datePublished\":\"2022-11-05T14:49:24+00:00\",\"dateModified\":\"2023-07-14T14:27:14+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg\",\"width\":800,\"height\":534},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo - Fieracavalli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/","og_locale":"it_IT","og_type":"article","og_title":"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo - Fieracavalli","og_url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2022-11-05T14:49:24+00:00","article_modified_time":"2023-07-14T14:27:14+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg","type":"image\/jpeg"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo","datePublished":"2022-11-05T14:49:24+00:00","dateModified":"2023-07-14T14:27:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/"},"wordCount":392,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg","articleSection":["A cavallo della sostenibilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/","url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/","name":"A Fieracavalli la quinta edizione del premio Carla Guglielmi alla miglior tesi sugli Interventi Assistiti con il Cavallo - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg","datePublished":"2022-11-05T14:49:24+00:00","dateModified":"2023-07-14T14:27:14+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/a-fieracavalli-la-quinta-edizione-del-premio-carla-guglielmi-alla-miglior-tesi-sugli-interventi-assistiti-con-il-cavallo\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/11\/Fieracavalli2022_EnneviFoto_Veronafiere__SM11264.jpg","width":800,"height":534},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/54250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=54250"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/54250\/revisions"}],"predecessor-version":[{"id":57563,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/54250\/revisions\/57563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/54298"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=54250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=54250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=54250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}