{"id":58747,"date":"2023-09-26T10:13:57","date_gmt":"2023-09-26T08:13:57","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=58747"},"modified":"2023-09-26T10:13:57","modified_gmt":"2023-09-26T08:13:57","slug":"a-fieracavalli-il-meglio-dellequitazione-iberica","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/","title":{"rendered":"A Fieracavalli il meglio dell\u2019equitazione iberica"},"content":{"rendered":"<p><span data-contrast=\"auto\">Il Padiglione 9 di Fieracavalli si trasforma, anche quest\u2019anno, nel \u201c<em>place to be<\/em>\u201d per tutti gli appassionati del mondo iberico!\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Grazie alla collaborazione con <\/span><b><span data-contrast=\"auto\">Equitaci\u00f3n Iberica Italia<\/span><\/b><span data-contrast=\"auto\"> &#8211; l\u2019associazione sportiva che ha come obiettivo quello di diffondere le discipline iberiche e classiche in tutta Italia &#8211; si potranno ammirare pi\u00f9 di <\/span><b><span data-contrast=\"auto\">150 elegantissimi<\/span><\/b><span data-contrast=\"auto\"> esemplari di cavalli iberici cimentarsi in show e competizioni di <\/span><b><span data-contrast=\"auto\">Doma Vaquera, Addestramento Classico e Arte dell&#8217;Eleganza<\/span><\/b><span data-contrast=\"auto\">.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Attesissime le spettacolari esibizioni dei campioni spagnoli di Doma Vaquera Jos\u00e9 Ramon Perez e Rafael Arcos Gonzales, cos\u00ec come le scenografiche performance di Cl\u00e9mence Faivre, una delle migliori interpreti di Gal\u00e0 Equestri a livello internazionale. Non mancheranno, inoltre, i pi\u00f9 alti esponenti delle scuole di Doma Classica e Alta Scuola, con i talentuosi maestri Johnny Bautista e Antonio Angulo.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ospite d&#8217;onore il presidente della Federazione Spagnola Jos\u00e9 Manuel Alonso.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Il meglio dell&#8217;equitazione iberica \u00e8 a Fieracavalli, dal <\/span><b><span data-contrast=\"auto\">9 al 12 novembre 2023<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Padiglione 9 di Fieracavalli si trasforma, anche quest\u2019anno, nel \u201cplace to be\u201d per tutti gli appassionati del mondo iberico!\u00a0\u00a0 Grazie alla collaborazione con Equitaci\u00f3n Iberica Italia &#8211; l\u2019associazione sportiva che ha come obiettivo quello di diffondere le discipline iberiche e classiche in tutta Italia &#8211; si potranno ammirare pi\u00f9 di 150 elegantissimi esemplari di [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":58771,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[841],"tags":[],"class_list":["post-58747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cavallo-spagnolo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Fieracavalli il meglio dell\u2019equitazione iberica - Fieracavalli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Fieracavalli il meglio dell\u2019equitazione iberica - Fieracavalli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-26T08:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/09\/EQUITAZION_IBERICA-e1695715994435.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"701\" \/>\n\t<meta property=\"og:image:height\" content=\"383\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"A Fieracavalli il meglio dell\u2019equitazione iberica\",\"datePublished\":\"2023-09-26T08:13:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/\"},\"wordCount\":160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EQUITAZION_IBERICA-e1695715994435.jpg\",\"articleSection\":[\"Cavallo Spagnolo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/\",\"name\":\"A Fieracavalli il meglio dell\u2019equitazione iberica - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EQUITAZION_IBERICA-e1695715994435.jpg\",\"datePublished\":\"2023-09-26T08:13:57+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/cavallo-spagnolo\\\/a-fieracavalli-il-meglio-dellequitazione-iberica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EQUITAZION_IBERICA-e1695715994435.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EQUITAZION_IBERICA-e1695715994435.jpg\",\"width\":701,\"height\":383},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Fieracavalli il meglio dell\u2019equitazione iberica - Fieracavalli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/","og_locale":"it_IT","og_type":"article","og_title":"A Fieracavalli il meglio dell\u2019equitazione iberica - Fieracavalli","og_url":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2023-09-26T08:13:57+00:00","og_image":[{"width":701,"height":383,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/09\/EQUITAZION_IBERICA-e1695715994435.jpg","type":"image\/jpeg"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"A Fieracavalli il meglio dell\u2019equitazione iberica","datePublished":"2023-09-26T08:13:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/"},"wordCount":160,"commentCount":0,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/09\/EQUITAZION_IBERICA-e1695715994435.jpg","articleSection":["Cavallo Spagnolo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/","url":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/","name":"A Fieracavalli il meglio dell\u2019equitazione iberica - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/09\/EQUITAZION_IBERICA-e1695715994435.jpg","datePublished":"2023-09-26T08:13:57+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/cavallo-spagnolo\/a-fieracavalli-il-meglio-dellequitazione-iberica\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/09\/EQUITAZION_IBERICA-e1695715994435.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/09\/EQUITAZION_IBERICA-e1695715994435.jpg","width":701,"height":383},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/58747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=58747"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/58747\/revisions"}],"predecessor-version":[{"id":58773,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/58747\/revisions\/58773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/58771"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=58747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=58747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=58747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}