{"id":71357,"date":"2023-11-11T09:08:43","date_gmt":"2023-11-11T08:08:43","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=71357"},"modified":"2024-09-11T17:42:19","modified_gmt":"2024-09-11T15:42:19","slug":"cavalli-in-villa-cresce-e-guarda-allestero","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/","title":{"rendered":"Cavalli in Villa cresce e guarda all\u2019estero"},"content":{"rendered":"<p><strong>Cavalli in Villa<\/strong> porta gli <strong>sport equestri<\/strong> fuori da maneggi e circoli ippici e li proietta in <strong>location<\/strong> da sogno <strong>immerse<\/strong> <strong>nell\u2019arte<\/strong> e nella <strong>cultura<\/strong> del territorio, dando vita ad un format originale e innovativo, promosso da Fise Veneto (Federazione italiana sport equestri) in collaborazione con Fise Nazionale, Ministero della Cultura, Sport &amp; Salute, con il sostegno della Regione del Veneto, dell\u2019Istituto Regionale Ville Venete (IRVV) e dell&#8217;Associazione Ville Venete. Un progetto capace di coniugare il fascino delle Ville palladiane alla magia del cavallo, la prestanza del gesto sportivo all\u2019incanto del territorio e della sua storia.<\/p>\n<p>Ad annunciarlo a<strong> Fieracavalli<\/strong> il Governatore del Veneto<strong> Luca Zaia<\/strong> insieme a <strong>Clara Campese<\/strong>, Presidente Fise Veneto e ideatrice del format, al Presidente Fise Nazionale <strong>Marco Di Paola<\/strong> e al Presidente di Veronafiere <strong>Federico Bricolo. <\/strong>Gli appuntamenti in calendario saranno 4 tra <strong>competizioni equestri, arte e musica<\/strong>: i primi 3\u00a0ad Abano Terme e Padova. Novit\u00e0 dell\u2019edizione 2024 il <strong>gemellaggio<\/strong> con la Sardegna, dove si terr\u00e0 la quarta e ultima tappa in provincia di Cagliari.<\/p>\n<p>Le parole di <strong>Zaia<\/strong>:<\/p>\n<p>\u00abAttendiamo in Veneto oltre 3mila persone tra cavalieri e staff e circa 250 cavalli per tappa. Una manifestazione sportiva e culturale che vedr\u00e0 coinvolti migliaia di atleti e appassionati, con una ricaduta socio-economica importante sul territorio.\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #003366;\"><strong><a style=\"color: #003366;\" href=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/11\/Cavalli-in-Villa-2024.pdf\">LEGGI QUI IL COMUNICATO STAMPA<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il cavallo come magnifico Alfiere di cultura, sport, arte, economia, solidariet\u00e0<\/p>\n","protected":false},"author":11,"featured_media":71537,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1107,1030],"tags":[],"class_list":["post-71357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-e-spettacoli","category-padiglione-4"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cavalli in Villa cresce e guarda all\u2019estero - Fieracavalli<\/title>\n<meta name=\"description\" content=\"Padiglione 4\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cavalli in Villa cresce e guarda all\u2019estero - Fieracavalli\" \/>\n<meta property=\"og:description\" content=\"Padiglione 4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-11T08:08:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T15:42:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/11\/copertinacavalli-in-villa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"Cavalli in Villa cresce e guarda all\u2019estero\",\"datePublished\":\"2023-11-11T08:08:43+00:00\",\"dateModified\":\"2024-09-11T15:42:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/\"},\"wordCount\":228,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/copertinacavalli-in-villa.jpeg\",\"articleSection\":[\"Intrattenimento e Spettacoli\",\"Padiglione 4\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/\",\"name\":\"Cavalli in Villa cresce e guarda all\u2019estero - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/copertinacavalli-in-villa.jpeg\",\"datePublished\":\"2023-11-11T08:08:43+00:00\",\"dateModified\":\"2024-09-11T15:42:19+00:00\",\"description\":\"Padiglione 4\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/padiglione-4\\\/cavalli-in-villa-cresce-e-guarda-allestero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/copertinacavalli-in-villa.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/copertinacavalli-in-villa.jpeg\",\"width\":1200,\"height\":676},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cavalli in Villa cresce e guarda all\u2019estero - Fieracavalli","description":"Padiglione 4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/","og_locale":"it_IT","og_type":"article","og_title":"Cavalli in Villa cresce e guarda all\u2019estero - Fieracavalli","og_description":"Padiglione 4","og_url":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2023-11-11T08:08:43+00:00","article_modified_time":"2024-09-11T15:42:19+00:00","og_image":[{"width":1200,"height":676,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/11\/copertinacavalli-in-villa.jpeg","type":"image\/jpeg"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"Cavalli in Villa cresce e guarda all\u2019estero","datePublished":"2023-11-11T08:08:43+00:00","dateModified":"2024-09-11T15:42:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/"},"wordCount":228,"commentCount":0,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/11\/copertinacavalli-in-villa.jpeg","articleSection":["Intrattenimento e Spettacoli","Padiglione 4"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/","url":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/","name":"Cavalli in Villa cresce e guarda all\u2019estero - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/11\/copertinacavalli-in-villa.jpeg","datePublished":"2023-11-11T08:08:43+00:00","dateModified":"2024-09-11T15:42:19+00:00","description":"Padiglione 4","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/padiglione-4\/cavalli-in-villa-cresce-e-guarda-allestero\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/11\/copertinacavalli-in-villa.jpeg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2023\/11\/copertinacavalli-in-villa.jpeg","width":1200,"height":676},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/71357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=71357"}],"version-history":[{"count":5,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/71357\/revisions"}],"predecessor-version":[{"id":71375,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/71357\/revisions\/71375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/71537"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=71357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=71357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=71357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}