{"id":77963,"date":"2024-05-30T11:30:58","date_gmt":"2024-05-30T09:30:58","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=77963"},"modified":"2024-10-30T12:58:58","modified_gmt":"2024-10-30T11:58:58","slug":"festival-haflinger","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/","title":{"rendered":"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige"},"content":{"rendered":"<p><span data-contrast=\"auto\">Fieracavalli, in programma a <\/span><b><span data-contrast=\"auto\">Verona <\/span><\/b><span data-contrast=\"auto\">dal <\/span><b><span data-contrast=\"auto\">7<\/span><\/b><span data-contrast=\"auto\"> al <\/span><b><span data-contrast=\"auto\">10 novembre<\/span><\/b><span data-contrast=\"auto\">, continua a rafforzare il suo <\/span><b><span data-contrast=\"auto\">percorso <\/span><\/b><span data-contrast=\"auto\">di <\/span><b><span data-contrast=\"auto\">valorizzazione delle razze equine italiane<\/span><\/b><span data-contrast=\"auto\">, scegliendo di collaborare, quest\u2019anno, con la <\/span><b><span data-contrast=\"auto\">Federazione Haflinger<\/span><\/b><span data-contrast=\"auto\">: l\u2019ente impegnato, da oltre un secolo, nel lavoro di conservazione della <\/span><b><span data-contrast=\"auto\">cultura<\/span><\/b><span data-contrast=\"auto\">, delle <\/span><b><span data-contrast=\"auto\">radici <\/span><\/b><span data-contrast=\"auto\">e del <\/span><b><span data-contrast=\"auto\">patrimonio <\/span><\/b><span data-contrast=\"auto\">storico dell\u2019<\/span><b><span data-contrast=\"auto\">Haflinger<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Questo esemplare, originario dell\u2019Alto Adige, \u00e8 da sempre ammirato per la sua <\/span><b><span data-contrast=\"auto\">dolcezza <\/span><\/b><span data-contrast=\"auto\">e <\/span><b><span data-contrast=\"auto\">affidabilit\u00e0<\/span><\/b><span data-contrast=\"auto\">, ma anche per il suo <\/span><b><span data-contrast=\"auto\">iconico manto sauro<\/span><\/b><span data-contrast=\"auto\"> e l&#8217;inconfondibile <\/span><b><span data-contrast=\"auto\">criniera bionda<\/span><\/b><span data-contrast=\"auto\">. Ancora oggi, inoltre, \u00e8 uno dei cavalli pi\u00f9 amati per le attivit\u00e0 di <\/span><b><span data-contrast=\"auto\">ippoterapia<\/span><\/b><span data-contrast=\"auto\">, per lo <\/span><b><span data-contrast=\"auto\">sport <\/span><\/b><span data-contrast=\"auto\">e per il <\/span><b><span data-contrast=\"auto\">tempo libero.<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Per tutti coloro che gi\u00e0 apprezzano le caratteristiche tipiche dell\u2019Haflinger e per chi, invece, ancora non le conosce, questo fine settimana \u00e8 in programma un evento imperdibile: il <\/span><b><span data-contrast=\"auto\">FESTIVAL HA<\/span><\/b><b><span data-contrast=\"auto\">LFLINGER con grande mostra provinciale.<\/span><\/b><span data-contrast=\"none\"> Presente alla manifestazione anche <\/span><b><span data-contrast=\"none\">Fieracavalli<\/span><\/b><span data-contrast=\"none\">, con uno <\/span><b><span data-contrast=\"none\">stand informativo<\/span><\/b><span data-contrast=\"none\"> dove gli appassionati del mondo equestre potranno scoprire le novit\u00e0 della nuova edizione.<\/span> <span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Dal <\/span><b><span data-contrast=\"auto\">31 maggio al 2 giugno,<\/span><\/b><span data-contrast=\"auto\"> a Sluderno sar\u00e0 possibile vedere riunita tuta la comunit\u00e0 Haflinger dell\u2019Alto Adige e festeggiare i <\/span><b><span data-contrast=\"auto\">150 anni <\/span><\/b><span data-contrast=\"auto\">della Federazione. Qui si potr\u00e0 conoscere da vicino il lavoro di <\/span><b><span data-contrast=\"auto\">selezione <\/span><\/b><span data-contrast=\"auto\">e <\/span><b><span data-contrast=\"auto\">valutazione <\/span><\/b><span data-contrast=\"auto\">degli oltre <\/span><b><span data-contrast=\"auto\">230 esemplari<\/span><\/b><span data-contrast=\"auto\"> &#8211; svolto dagli allevatori partecipanti &#8211; senza dimenticare una parte dedicata all\u2019intrattenimento con <\/span><b><span data-contrast=\"none\">musica <\/span><\/b><span data-contrast=\"none\">blues e folk <\/span><b><span data-contrast=\"none\">live<\/span><\/b><span data-contrast=\"none\">, food truck di specialit\u00e0 altoatesine, una <\/span><b><span data-contrast=\"none\">sfilata di carrozze<\/span><\/b><span data-contrast=\"none\"> e &#8211; per i pi\u00f9 piccoli &#8211; l\u2019attesissimo battesimo della sella. <\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Sabato pomeriggio alle ore 15:45, inoltre, presso il <\/span><b><span data-contrast=\"none\">Museo della Val Venosta <\/span><\/b><span data-contrast=\"none\">(VUSEUM) di Sluderno, si terr\u00e0 la presentazione del libro <\/span><b><span data-contrast=\"none\">&#8220;150 anni di allevamento Haflinger \u2013 Storia e storie&#8221;<\/span><\/b><span data-contrast=\"none\"> del dottor <\/span><b><span data-contrast=\"none\">Erich Messner<\/span><\/b><span data-contrast=\"none\">.\u00a0 Subito dopo, alle ore 17:00, il museo ospiter\u00e0 anche il <\/span><b><span data-contrast=\"none\">Convegno Mondiale Haflinger<\/span><\/b><span data-contrast=\"none\">, durante il quale <\/span><b><span data-contrast=\"none\">esperti <\/span><\/b><span data-contrast=\"none\">della ricerca e della <\/span><b><span data-contrast=\"none\">selezione equina<\/span><\/b><span data-contrast=\"none\"> approfondiranno temi legati alla <\/span><b><span data-contrast=\"none\">scienza <\/span><\/b><span data-contrast=\"none\">e alla <\/span><b><span data-contrast=\"none\">conoscenza <\/span><\/b><span data-contrast=\"none\">della razza Haflinger.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\"><br \/>\n<\/span><span data-contrast=\"none\">Per scoprire il programma completo del weekend dedicato all\u2019Haflinger, basta visitare il sito internet: <\/span><a href=\"http:\/\/www.haflinger-festival.eu\/\"><span data-contrast=\"none\">www.haflinger-festival.eu<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">Sar\u00e0 possibile ammirare da vicino i bellissimi esemplari di <\/span><b><span data-contrast=\"auto\">Haflinger <\/span><\/b><span data-contrast=\"auto\">anche a <\/span><b><span data-contrast=\"auto\">Fieracavalli<\/span><\/b><span data-contrast=\"auto\">, in scena con la sua <\/span><b><span data-contrast=\"auto\">126\u00aa edizione<\/span><\/b><span data-contrast=\"auto\"> dal <\/span><b><span data-contrast=\"auto\">7 al 10 novembre a Verona.<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fieracavalli, in programma a Verona dal 7 al 10 novembre, continua a rafforzare il suo percorso di valorizzazione delle razze equine italiane, scegliendo di collaborare, quest\u2019anno, con la Federazione Haflinger: l\u2019ente impegnato, da oltre un secolo, nel lavoro di conservazione della cultura, delle radici e del patrimonio storico dell\u2019Haflinger.\u00a0 Questo esemplare, originario dell\u2019Alto Adige, \u00e8 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":77964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1039],"tags":[],"class_list":["post-77963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-razze-italiane"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige - Fieracavalli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige - Fieracavalli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-30T09:30:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T11:58:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/05\/WEN_5253-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige\",\"datePublished\":\"2024-05-30T09:30:58+00:00\",\"dateModified\":\"2024-10-30T11:58:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/\"},\"wordCount\":357,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WEN_5253-1.jpg\",\"articleSection\":[\"Razze italiane\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/\",\"name\":\"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WEN_5253-1.jpg\",\"datePublished\":\"2024-05-30T09:30:58+00:00\",\"dateModified\":\"2024-10-30T11:58:58+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/razze-italiane\\\/festival-haflinger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WEN_5253-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WEN_5253-1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige - Fieracavalli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/","og_locale":"it_IT","og_type":"article","og_title":"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige - Fieracavalli","og_url":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2024-05-30T09:30:58+00:00","article_modified_time":"2024-10-30T11:58:58+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/05\/WEN_5253-1.jpg","type":"image\/jpeg"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige","datePublished":"2024-05-30T09:30:58+00:00","dateModified":"2024-10-30T11:58:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/"},"wordCount":357,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/05\/WEN_5253-1.jpg","articleSection":["Razze italiane"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/","url":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/","name":"Festival Haflinger: a Sluderno l\u2019appuntamento per conoscere da vicino la razza tipica dell\u2019Alto Adige - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/05\/WEN_5253-1.jpg","datePublished":"2024-05-30T09:30:58+00:00","dateModified":"2024-10-30T11:58:58+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/razze-italiane\/festival-haflinger\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/05\/WEN_5253-1.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/05\/WEN_5253-1.jpg","width":1200,"height":800},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/77963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=77963"}],"version-history":[{"count":5,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/77963\/revisions"}],"predecessor-version":[{"id":77983,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/77963\/revisions\/77983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/77964"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=77963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=77963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=77963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}