{"id":78129,"date":"2024-06-12T14:02:31","date_gmt":"2024-06-12T12:02:31","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=78129"},"modified":"2024-06-19T12:08:05","modified_gmt":"2024-06-19T10:08:05","slug":"premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/","title":{"rendered":"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione"},"content":{"rendered":"<p><span data-contrast=\"auto\">Per la sua <strong>126\u00aa edizione<\/strong>, Fieracavalli torna a supportare in qualit\u00e0 di partner e sostenitore<\/span><span data-contrast=\"auto\"> il <\/span><b><span data-contrast=\"auto\">Premio Carla Guglielmi<\/span><\/b><span data-contrast=\"auto\">, la borsa di studio assegnata annualmente da <\/span><b><span data-contrast=\"auto\">Fondazione Fevoss Santa Toscana<\/span><\/b><span data-contrast=\"auto\"> agli studenti e alle studentesse che abbiano scelto per la loro tesi di laurea e\/o dottorato, il tema della terapia assistita con il cavallo.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Giunto alla sua settima edizione, il <\/span><a href=\"https:\/\/www.fondazionefevoss.org\/wp-content\/uploads\/2024\/05\/BANDO-CONCORSO-GUGLIELMI-7%C2%B0-EDIZ_2024_NFC_web.pdf\"><span data-contrast=\"none\">bando<\/span><\/a><span data-contrast=\"auto\"> vuole coinvolgere tutti coloro che abbiano conseguito la Laurea, la Laurea Magistrale, il Dottorato di Ricerca o il Master Universitario con una tesi dal tema \u201cG<\/span><i><span data-contrast=\"auto\">iovani e Cavalli: valenza degli interventi assistiti con il cavallo nel disagio giovanile<\/span><\/i><span data-contrast=\"auto\">\u201d, discussa tra l\u2019anno <\/span><b><span data-contrast=\"auto\">2021 e il 30 settembre 2024<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Gli elaborati, nello specifico, dovranno trattare il tema della <\/span><b><span data-contrast=\"auto\">giovent\u00f9 <\/span><\/b><span data-contrast=\"auto\">e<\/span><span data-contrast=\"auto\"> delle <\/span><b><span data-contrast=\"auto\">problematiche <\/span><\/b><span data-contrast=\"auto\">a essa collegate, con un focus su come gli <\/span><b><span data-contrast=\"auto\">interventi assistiti con il cavallo<\/span><\/b><span data-contrast=\"auto\"> possano rappresentare non solo un valido <\/span><b><span data-contrast=\"auto\">supporto <\/span><\/b><span data-contrast=\"auto\">in situazioni di <\/span><b><span data-contrast=\"auto\">difficolt\u00e0 psicofisica, <\/span><\/b><span data-contrast=\"auto\">ma anche uno<\/span><b><span data-contrast=\"auto\"> stimolo <\/span><\/b><span data-contrast=\"auto\">positivo <\/span><b><span data-contrast=\"auto\">nel percorso di crescita<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335557856&quot;:16777215,&quot;335559738&quot;:0,&quot;335559739&quot;:216,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Una commissione composta da <\/span><b><span data-contrast=\"auto\">docenti, medici, veterinari ed esperti<\/span><\/b><span data-contrast=\"auto\"> selezioner\u00e0 &#8211; alla chiusura del bando &#8211; il lavoro pi\u00f9 meritevole, assegnando al vincitore un premio di <\/span><b><span data-contrast=\"auto\">1.500\u20ac <\/span><\/b><span data-contrast=\"auto\">che verr\u00e0 consegnato proprio durante la <\/span><b><span data-contrast=\"auto\">126\u00aa <\/span><\/b><span data-contrast=\"auto\">edizione di <\/span><b><span data-contrast=\"auto\">Fieracavalli<\/span><\/b><span data-contrast=\"auto\">, in programma a <\/span><b><span data-contrast=\"auto\">Verona dal 7 al 10<\/span><\/b> <b><span data-contrast=\"auto\">novembre<\/span><\/b><span data-contrast=\"auto\">.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La tesi vincitrice, inoltre, sar\u00e0 pubblicata sulla collana \u201cIl nitrito che cura\u201d.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Tutte le informazioni per partecipare al bando sono consultabili sul <\/span><a href=\"http:\/\/fondazionefevoss.org\/premio-carla-guglielmi\/\"><span data-contrast=\"none\">sito della fondazione Fevoss<\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aperto il bando di concorso per la borsa di studio dal valore di 1.500\u20ac assegnata dalla Fondazione Fevoss Santa Toscana al miglior elaborato dal tema \u201cGiovani e Cavalli: valenza degli interventi assistiti con il cavallo nel disagio giovanile\u201d<\/p>\n","protected":false},"author":11,"featured_media":78130,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[832],"tags":[],"class_list":["post-78129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-cavallo-della-sostenibilita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione - Fieracavalli<\/title>\n<meta name=\"description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione - Fieracavalli\" \/>\n<meta property=\"og:description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T12:02:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T10:08:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-37.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione\",\"datePublished\":\"2024-06-12T12:02:31+00:00\",\"dateModified\":\"2024-06-19T10:08:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/\"},\"wordCount\":232,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Progetto-senza-titolo-37.png\",\"articleSection\":[\"A cavallo della sostenibilit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/\",\"name\":\"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Progetto-senza-titolo-37.png\",\"datePublished\":\"2024-06-12T12:02:31+00:00\",\"dateModified\":\"2024-06-19T10:08:05+00:00\",\"description\":\"A cavallo della sostenibilit\u00e0\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Progetto-senza-titolo-37.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Progetto-senza-titolo-37.png\",\"width\":1200,\"height\":600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione - Fieracavalli","description":"A cavallo della sostenibilit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/","og_locale":"it_IT","og_type":"article","og_title":"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione - Fieracavalli","og_description":"A cavallo della sostenibilit\u00e0","og_url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2024-06-12T12:02:31+00:00","article_modified_time":"2024-06-19T10:08:05+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-37.png","type":"image\/png"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione","datePublished":"2024-06-12T12:02:31+00:00","dateModified":"2024-06-19T10:08:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/"},"wordCount":232,"commentCount":0,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-37.png","articleSection":["A cavallo della sostenibilit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/","url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/","name":"Premio Nazionale Carla Guglielmi: aperto il bando della 7\u1d43 edizione - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-37.png","datePublished":"2024-06-12T12:02:31+00:00","dateModified":"2024-06-19T10:08:05+00:00","description":"A cavallo della sostenibilit\u00e0","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/premio-nazionale-carla-guglielmi-aperto-il-bando-della-7%e1%b5%83-edizione\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-37.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-37.png","width":1200,"height":600},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/78129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=78129"}],"version-history":[{"count":1,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/78129\/revisions"}],"predecessor-version":[{"id":78132,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/78129\/revisions\/78132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/78130"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=78129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=78129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=78129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}