{"id":97982,"date":"2024-11-08T18:17:32","date_gmt":"2024-11-08T17:17:32","guid":{"rendered":"https:\/\/www.fieracavalli.it\/?p=97982"},"modified":"2024-11-08T18:19:22","modified_gmt":"2024-11-08T17:19:22","slug":"riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico","status":"publish","type":"post","link":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/","title":{"rendered":"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico"},"content":{"rendered":"<p><span class=\"TextRun SCXW227873006 BCX8\" lang=\"IT-IT\" xml:lang=\"IT-IT\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW227873006 BCX8\">Il progetto <strong>\u201cRiding the Blue\u201d <\/strong><\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">&#8211; <\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">realizzato grazie alla collaborazione tra <strong>Fieracavalli, FISE, Azienda Ospedaliera Universitaria Integrata di Verona, Azienda ULSS 9 Scaligera e Regione del Veneto<\/strong> <\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">&#8211; <\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">conferma <strong>l\u2019efficacia dell\u2019Intervento Assistito con gli Animali<\/strong><\/span><strong><span class=\"NormalTextRun SCXW227873006 BCX8\">,<\/span><\/strong><span class=\"NormalTextRun SCXW227873006 BCX8\"> e in particolare con il <strong>cavallo<\/strong><\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">,<\/span><span class=\"NormalTextRun SCXW227873006 BCX8\"> nell\u2019ambito dei<strong> Disturbi dello Spettro Autistico<\/strong><\/span><span class=\"NormalTextRun SCXW227873006 BCX8\"> con un obiettivo importante:<\/span><span class=\"NormalTextRun SCXW227873006 BCX8\"><strong> estendere la ricerca<\/strong> su tutto il territorio nazionale coinvolgendo ulteriori 150 partecipanti, in modo da <strong>ottenere<\/strong> <strong>dati<\/strong> ancora pi\u00f9 <strong>significativi<\/strong> che <\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">permetterebbero<\/span><span class=\"NormalTextRun SCXW227873006 BCX8\"> a questo tipo di trattamento non solo di <strong>rappresentare un valido intervento supplementare o integrativo<\/strong><\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">, <\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">ma di rientrare nell\u2019ambito <\/span><span class=\"NormalTextRun SCXW227873006 BCX8\">degli<\/span><span class=\"NormalTextRun SCXW227873006 BCX8\"> \u201capprocci ecologici\u201d considerati dalla letteratura scientifica internazionale.\u202f<\/span><\/span><span class=\"EOP SCXW227873006 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Oggi sono stati presentati i risultati di un altro anno di sperimentazione del progetto pilota \u201c<\/span><b><span data-contrast=\"none\">Riding the Blue\u201d <\/span><\/b><span data-contrast=\"none\">dedicato alla <strong>terapia assistita con i cavalli per bambini e ragazzi con Sindrome dello Spettro Autistico<\/strong>.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">\u202f<\/span><span data-contrast=\"none\">Ai 15 partecipanti iniziali alla sperimentazione dislocati nel solo Veneto, si \u00e8 arrivati \u2013 nel 2022 &#8211; a <strong>60 soggetti di 6 regioni<\/strong> italiane, ampliando ulteriormente lo studio, nel 2023, grazie al coinvolgimento di <strong>95 bambini e ragazzi tra gli 8 e i 13 anni di 10 regioni italiane<\/strong>: Veneto, Lombardia, Friuli-Venezia Giulia, Toscana, Umbria, Lazio, Campania, Puglia, Calabria e Sicilia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">I <strong>risultati<\/strong> &#8211; elaborati e analizzati dal <strong>Centro Regionale Disturbi dello Spettro Autistico di Verona<\/strong> \u2013 sono sorprendenti ed evidenziando un miglioramento del funzionamento del comportamento adattivo, una riduzione delle disprassie, un incremento della coordinazione motoria e delle abilit\u00e0 di processazione sensoriale, risposte che si declinano in effetti molto positivi sulla qualit\u00e0 della vita quotidiana dei bambini e ragazzi, ma anche delle famiglie e delle persone che li circondano.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il progetto \u201cRiding the Blue\u201d &#8211; realizzato grazie alla collaborazione tra Fieracavalli, FISE, Azienda Ospedaliera Universitaria Integrata di Verona, Azienda ULSS 9 Scaligera e Regione del Veneto &#8211; conferma l\u2019efficacia dell\u2019Intervento Assistito con gli Animali, e in particolare con il cavallo, nell\u2019ambito dei Disturbi dello Spettro Autistico con un obiettivo importante: estendere la ricerca su [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":97991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[832],"tags":[],"class_list":["post-97982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-cavallo-della-sostenibilita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico - Fieracavalli<\/title>\n<meta name=\"description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico - Fieracavalli\" \/>\n<meta property=\"og:description\" content=\"A cavallo della sostenibilit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieracavalli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fieracavalli\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T17:17:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T17:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/11\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/\"},\"author\":{\"name\":\"Chiara\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\"},\"headline\":\"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico\",\"datePublished\":\"2024-11-08T17:17:32+00:00\",\"dateModified\":\"2024-11-08T17:19:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg\",\"articleSection\":[\"A cavallo della sostenibilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/\",\"name\":\"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico - Fieracavalli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg\",\"datePublished\":\"2024-11-08T17:17:32+00:00\",\"dateModified\":\"2024-11-08T17:19:22+00:00\",\"description\":\"A cavallo della sostenibilit\u00e0\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/a-cavallo-della-sostenibilita\\\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"name\":\"FIERACAVALLI\",\"description\":\"Verona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#organization\",\"name\":\"FIERACAVALLI\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"contentUrl\":\"https:\\\/\\\/www.fieracavalli.it\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LOGO_Jumping.png\",\"width\":283,\"height\":236,\"caption\":\"FIERACAVALLI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fieracavalli\",\"https:\\\/\\\/www.instagram.com\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fieracavalli\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fieracavalli\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/login?redirect_url=https:\\\/\\\/www.tiktok.com\\\/@fieracavalliverona&lang=en&enter_method=mandatory\",\"https:\\\/\\\/x.com\\\/i\\\/flow\\\/login?redirect_after_login=\\\/fieracavalli\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fieracavalli.it\\\/it\\\/#\\\/schema\\\/person\\\/edcdf01142f6d1cd5c94e02b72b4079b\",\"name\":\"Chiara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g\",\"caption\":\"Chiara\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico - Fieracavalli","description":"A cavallo della sostenibilit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/","og_locale":"it_IT","og_type":"article","og_title":"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico - Fieracavalli","og_description":"A cavallo della sostenibilit\u00e0","og_url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/","og_site_name":"Fieracavalli","article_publisher":"https:\/\/www.facebook.com\/fieracavalli","article_published_time":"2024-11-08T17:17:32+00:00","article_modified_time":"2024-11-08T17:19:22+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/11\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg","type":"image\/jpeg"}],"author":"Chiara","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Chiara","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/#article","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/"},"author":{"name":"Chiara","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b"},"headline":"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico","datePublished":"2024-11-08T17:17:32+00:00","dateModified":"2024-11-08T17:19:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/"},"wordCount":275,"publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/11\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg","articleSection":["A cavallo della sostenibilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/","url":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/","name":"Riding The Blue: presentati gli aggiornamenti del protocollo di terapia assistita con i cavalli per persone con disturbo dello spettro autistico - Fieracavalli","isPartOf":{"@id":"https:\/\/www.fieracavalli.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/#primaryimage"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/11\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg","datePublished":"2024-11-08T17:17:32+00:00","dateModified":"2024-11-08T17:19:22+00:00","description":"A cavallo della sostenibilit\u00e0","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/a-cavallo-della-sostenibilita\/riding-the-blue-presentati-gli-aggiornamenti-del-protocollo-di-terapia-assistita-con-i-cavalli-per-persone-con-disturbo-dello-spettro-autistico\/#primaryimage","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/11\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2024\/11\/Fieracavalli2024_Veronafiere_EnneviFoto__DSCF3213.jpg","width":1200,"height":800},{"@type":"WebSite","@id":"https:\/\/www.fieracavalli.it\/it\/#website","url":"https:\/\/www.fieracavalli.it\/it\/","name":"FIERACAVALLI","description":"Verona","publisher":{"@id":"https:\/\/www.fieracavalli.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieracavalli.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fieracavalli.it\/it\/#organization","name":"FIERACAVALLI","url":"https:\/\/www.fieracavalli.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","contentUrl":"https:\/\/www.fieracavalli.it\/wp-content\/uploads\/2022\/08\/LOGO_Jumping.png","width":283,"height":236,"caption":"FIERACAVALLI"},"image":{"@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fieracavalli","https:\/\/www.instagram.com\/fieracavalli\/","https:\/\/www.youtube.com\/user\/fieracavalli","https:\/\/www.linkedin.com\/company\/fieracavalli\/","https:\/\/www.tiktok.com\/login?redirect_url=https:\/\/www.tiktok.com\/@fieracavalliverona&lang=en&enter_method=mandatory","https:\/\/x.com\/i\/flow\/login?redirect_after_login=\/fieracavalli"]},{"@type":"Person","@id":"https:\/\/www.fieracavalli.it\/it\/#\/schema\/person\/edcdf01142f6d1cd5c94e02b72b4079b","name":"Chiara","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/538ed07ecc6c79490a9f2b9058134493967e256d8751749d4388d99cf700a7f4?s=96&d=mm&r=g","caption":"Chiara"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/97982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/comments?post=97982"}],"version-history":[{"count":3,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/97982\/revisions"}],"predecessor-version":[{"id":97996,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/posts\/97982\/revisions\/97996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media\/97991"}],"wp:attachment":[{"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/media?parent=97982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/categories?post=97982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fieracavalli.it\/it\/wp-json\/wp\/v2\/tags?post=97982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}